{"id":2285,"date":"2024-05-22T11:22:48","date_gmt":"2024-05-22T11:22:48","guid":{"rendered":"https:\/\/eralcapital.ltd\/sign-up"},"modified":"2024-09-10T13:52:40","modified_gmt":"2024-09-10T13:52:40","slug":"sign-up","status":"publish","type":"page","link":"https:\/\/eralcapital.ltd\/ro\/sign-up","title":{"rendered":"\u00cenregistrare"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2285\" class=\"elementor elementor-2285\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ef89b9b elementor-reverse-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ef89b9b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25c7dad1\" data-id=\"25c7dad1\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45a4e7f9 elementor-button-align-center elementor-widget elementor-widget-form\" data-id=\"45a4e7f9\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.21.0 - 30-04-2024 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#babfc5}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-field-type-tel input{direction:inherit}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button>span{display:flex;justify-content:center;align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal;flex-grow:0}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" id=\"cp-crm-sign-up-form\" name=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"2285\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"45a4e7f9\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-firstName elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-firstName\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNume\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[firstName]\" id=\"form-field-firstName\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Numele dvs.\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-lastName elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-lastName\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tPrenume\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[lastName]\" id=\"form-field-lastName\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Prenumele dvs.\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-contacts__email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-contacts__email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[contacts__email]\" id=\"form-field-contacts__email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Adresa dvs. de email\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-password elementor-field-group elementor-column elementor-field-group-password elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-password\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tParola\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"password\" name=\"form_fields[password]\" id=\"form-field-password\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Minim 8 caractere\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-address__countryCode elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-address__countryCode\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u021aara\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[address__countryCode]\" id=\"form-field-address__countryCode\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t<option value=\"\u021aara\">\u021aara<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"AF\">Afghanistan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"AL\">Albania<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"DZ\">Algeria<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"AS\">American Samoa<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"AD\">Andorra<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"AO\">Angola<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"AI\">Anguilla<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"AQ\">Antarctica<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"AR\">Argentina<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"AM\">Armenia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"AW\">Aruba<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"AU\">Australia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"AT\">Austria<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"AZ\">Azerbaijan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BS\">Bahamas<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BH\">Bahrain<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BD\">Bangladesh<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BB\">Barbados<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BY\">Belarus<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BE\">Belgium<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BZ\">Belize<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BJ\">Benin<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BM\">Bermuda<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BT\">Bhutan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BO\">Bolivia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BQ\">Bonaire<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BA\">Bosnia and Herzegovina<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BW\">Botswana<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BV\">Bouvet Island<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BR\">Brazil<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"IO\">British Indian Ocean Territory<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BN\">Brunei Darussalam<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BG\">Bulgaria<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BF\">Burkina Faso<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"BI\">Burundi<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"KH\">Cambodia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CM\">Cameroon<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CA\">Canada<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CV\">Cape Verde<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"KY\">Cayman Islands<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CF\">Central African Republic<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TD\">Chad<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CL\">Chile<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CN\">China<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CX\">Christmas Island<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CC\">Cocos (Keeling) Islands<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CO\">Colombia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"KM\">Comoros<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CG\">Congo<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CD\">Congo, the Democratic Republic of the<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CK\">Cook Islands<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CR\">Costa Rica<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CI\">C\u00c3\u00b4te d&#039;Ivoire<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"HR\">Croatia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CU\">Cuba<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CY\">Cyprus<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CZ\">Czech Republic<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"DK\">Denmark<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"DJ\">Djibouti<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"DM\">Dominica<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"DO\">Dominican Republic<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"EC\">Ecuador<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"EG\">Egypt<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SV\">El Salvador<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GQ\">Equatorial Guinea<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"ER\">Eritrea<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"EE\">Estonia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"ET\">Ethiopia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"FK\">Falkland Islands<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"FO\">Faroe Islands<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"FJ\">Fiji<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"FI\">Finland<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"FR\">France<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GF\">French Guiana<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"PF\">French Polynesia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TF\">French Southern Territories<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GA\">Gabon<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GM\">Gambia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GE\">Georgia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"DE\">Germany<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GH\">Ghana<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GI\">Gibraltar<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GR\">Greece<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GL\">Greenland<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GD\">Grenada<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GP\">Guadeloupe<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GU\">Guam<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GT\">Guatemala<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GG\">Guernsey<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GN\">Guinea<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GW\">Guinea-Bissau<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GY\">Guyana<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"HT\">Haiti<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"VA\">Holy See<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"HN\">Honduras<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"HK\">Hong Kong<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"HU\">Hungary<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"IS\">Iceland<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"IN\">India<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"ID\">Indonesia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"IR\">Iran<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"IQ\">Iraq<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"IE\">Ireland<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"IM\">Isle of Man<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"IL\">Israel<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"IT\">Italy<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"JM\">Jamaica<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"JP\">Japan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"JE\">Jersey<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"JO\">Jordan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"KZ\">Kazakhstan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"KE\">Kenya<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"KI\">Kiribati<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"KR\">Korea<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"KW\">Kuwait<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"KG\">Kyrgyzstan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"LA\">Lao People&#039;s Democratic Republic<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"LV\">Latvia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"LB\">Lebanon<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"LS\">Lesotho<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"LR\">Liberia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"LY\">Libya<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"LI\">Liechtenstein<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"LT\">Lithuania<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"LU\">Luxembourg<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MO\">Macao<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MK\">Macedonia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MG\">Madagascar<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MW\">Malawi<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MY\">Malaysia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MV\">Maldives<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"ML\">Mali<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MT\">Malta<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MH\">Marshall Islands<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MQ\">Martinique<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MR\">Mauritania<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MU\">Mauritius<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"YT\">Mayotte<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MX\">Mexico<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"FM\">Micronesia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MD\">Moldova<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MC\">Monaco<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MN\">Mongolia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"ME\">Montenegro<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MS\">Montserrat<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MA\">Morocco<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MZ\">Mozambique<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MM\">Myanmar<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"NA\">Namibia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"NR\">Nauru<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"NP\">Nepal<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"NL\">Netherlands<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"NC\">New Caledonia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"NZ\">New Zealand<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"NI\">Nicaragua<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"NE\">Niger<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"NG\">Nigeria<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"NU\">Niue<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"NF\">Norfolk Island<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MP\">Northern Mariana Islands<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"NO\">Norway<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"OM\">Oman<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"PK\">Pakistan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"PW\">Palau<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"PS\">Palestine<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"PA\">Panama<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"PG\">Papua New Guinea<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"PY\">Paraguay<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"PE\">Peru<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"PH\">Philippines<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"PN\">Pitcairn<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"PL\">Poland<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"PT\">Portugal<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"PR\">Puerto Rico<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"QA\">Qatar<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"RE\">R\u00c3\u00a9union<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"RO\">Romania<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"RU\">Russian Federation<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"RW\">Rwanda<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SH\">Saint Helena<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"KN\">Saint Kitts and Nevis<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"LC\">Saint Lucia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"MF\">Saint Martin<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"PM\">Saint Pierre<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"VC\">Saint Vincent<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"WS\">Samoa<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SM\">San Marino<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"ST\">Sao Tome and Principe<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SA\">Saudi Arabia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SN\">Senegal<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"RS\">Serbia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SC\">Seychelles<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SL\">Sierra Leone<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SG\">Singapore<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SX\">Sint Maarten<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SK\">Slovakia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SI\">Slovenia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SB\">Solomon Islands<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SO\">Somalia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"ZA\">South Africa<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GS\">South Georgia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SS\">South Sudan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"ES\">Spain<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"LK\">Sri Lanka<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SD\">Sudan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SR\">Suriname<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SJ\">Svalbard<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SZ\">Swaziland<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SE\">Sweden<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"CH\">Switzerland<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"SY\">Syrian Arab Republic<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TW\">Taiwan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TJ\">Tajikistan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TZ\">Tanzania<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TH\">Thailand<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TL\">Timor-Leste<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TG\">Togo<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TK\">Tokelau<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TO\">Tonga<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TT\">Trinidad and Tobago<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TN\">Tunisia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TR\">Turkey<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TM\">Turkmenistan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TC\">Turks and Caicos Islands<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"TV\">Tuvalu<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"UG\">Uganda<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"UA\">Ukraine<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"AE\">United Arab Emirates<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GB\">United Kingdom<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"US\">United States<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"UM\">United States Minor Outlying Islands<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"UY\">Uruguay<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"UZ\">Uzbekistan<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"VU\">Vanuatu<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"VE\">Venezuela<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"VN\">Viet Nam<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"VG\">Virgin Islands, British<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"VI\">Virgin Islands, U.S.<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"WF\">Wallis and Futuna<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"EH\">Western Sahara<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"YE\">Yemen<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"ZM\">Zambia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"ZW\">Zimbabwe<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-contacts__phone elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-contacts__phone\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTelefon\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[contacts__phone]\" id=\"form-field-contacts__phone\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Num\u0103rul dvs. de telefon\" required=\"required\" aria-required=\"true\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_4 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_4]\" id=\"form-field-field_4\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\" aria-required=\"true\">\n\t\t\t\t<label for=\"form-field-field_4\">Am peste 18 ani.<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_1 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_1]\" id=\"form-field-field_1\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\" aria-required=\"true\">\n\t\t\t\t<label for=\"form-field-field_1\">Nu sunt cet\u0103\u021bean al SUA.<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_2 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_2]\" id=\"form-field-field_2\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\" aria-required=\"true\">\n\t\t\t\t<label for=\"form-field-field_2\">Am citit \u0219i acceptat termenii \u0219i condi\u021biile Acordului de client, Politica companiei, Politica de confiden\u021bialitate, Termenii \u0219i condi\u021biile \u0219i Declara\u021bia de renun\u021bare. De asemenea, recunosc \u0219i sunt de acord cu prelucrarea datelor mele personale \u00een conformitate cu Eral Capital.<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_3 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_3]\" id=\"form-field-field_3\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\" aria-required=\"true\">\n\t\t\t\t<label for=\"form-field-field_3\">Doresc s\u0103 deschid un cont la Eral Capital. Confirm c\u0103 m-am adresat la Eral Capital din propria mea voin\u021b\u0103 \u0219i ini\u021biativ\u0103. De asemenea, sunt de acord ca reprezentan\u021bii companiei s\u0103 m\u0103 contacteze telefonic \u0219i\/sau prin email.<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-referralHash elementor-col-100\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-affiliate__externalAffiliateId elementor-col-100\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-lang elementor-col-100\">\n\t\t\t\t\t<input size=\"1\" type=\"hidden\" value=\"ro\" name=\"form_fields[lang]\" id=\"form-field-lang\">\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-md\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\" elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00ceNREGISTRARE<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-373bfc3a elementor-widget elementor-widget-text-editor\" data-id=\"373bfc3a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p style=\"font-size: 1.35em; text-align: center; color: #000;\">Sunte\u021bi deja \u00eenregistrat?\n<a style=\"color: #CB8900;\" href=\"\/ro\/sign-in\">Autentifica\u021bi-v\u0103<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sunte\u021bi deja \u00eenregistrat? Autentifica\u021bi-v\u0103<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/eralcapital.ltd\/ro\/wp-json\/wp\/v2\/pages\/2285"}],"collection":[{"href":"https:\/\/eralcapital.ltd\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eralcapital.ltd\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eralcapital.ltd\/ro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eralcapital.ltd\/ro\/wp-json\/wp\/v2\/comments?post=2285"}],"version-history":[{"count":5,"href":"https:\/\/eralcapital.ltd\/ro\/wp-json\/wp\/v2\/pages\/2285\/revisions"}],"predecessor-version":[{"id":2321,"href":"https:\/\/eralcapital.ltd\/ro\/wp-json\/wp\/v2\/pages\/2285\/revisions\/2321"}],"wp:attachment":[{"href":"https:\/\/eralcapital.ltd\/ro\/wp-json\/wp\/v2\/media?parent=2285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}