{"id":2251,"date":"2024-05-18T07:53:54","date_gmt":"2024-05-18T07:53:54","guid":{"rendered":"https:\/\/eralcapital.ltd\/company"},"modified":"2024-09-10T13:52:35","modified_gmt":"2024-09-10T13:52:35","slug":"company","status":"publish","type":"page","link":"https:\/\/eralcapital.ltd\/ro\/company","title":{"rendered":"Despre companie"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2251\" class=\"elementor elementor-2251\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-03bf10f elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"03bf10f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61e2b66\" data-id=\"61e2b66\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fb9c19f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb9c19f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-0f2c450\" data-id=\"0f2c450\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21b34da elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-bdt-advanced-counter\" data-id=\"21b34da\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"bdt-advanced-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-counter\" data-settings=\"{&quot;id&quot;:&quot;bdt-ep-advanced-counter-data-21b34da&quot;,&quot;countNumber&quot;:1,&quot;language&quot;:[&quot;0&quot;,&quot;1&quot;,&quot;2&quot;,&quot;3&quot;,&quot;4&quot;,&quot;5&quot;,&quot;6&quot;,&quot;7&quot;,&quot;8&quot;,&quot;9&quot;],&quot;duration&quot;:&quot;2&quot;,&quot;useEasing&quot;:&quot;yes&quot;,&quot;useGrouping&quot;:&quot;no&quot;,&quot;decimalSymbol&quot;:&quot;.&quot;,&quot;counterSuffix&quot;:&quot; milion&quot;}\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-content\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-number\">\n\t\t\t\t<span class=\"bdt-count-this\" id=\"bdt-ep-advanced-counter-data-21b34da\" >\n\t\t\t\t\t1\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p\t\t\t\t\t\tclass=\"bdt-ep-advanced-counter-text\">\n\t\t\t\t\t\tClien\u021bi activi\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8915542\" data-id=\"8915542\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e14dc78 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-bdt-advanced-counter\" data-id=\"e14dc78\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"bdt-advanced-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-counter\" data-settings=\"{&quot;id&quot;:&quot;bdt-ep-advanced-counter-data-e14dc78&quot;,&quot;countStart&quot;:1,&quot;countNumber&quot;:62,&quot;language&quot;:[&quot;0&quot;,&quot;1&quot;,&quot;2&quot;,&quot;3&quot;,&quot;4&quot;,&quot;5&quot;,&quot;6&quot;,&quot;7&quot;,&quot;8&quot;,&quot;9&quot;],&quot;duration&quot;:&quot;2&quot;,&quot;useEasing&quot;:&quot;yes&quot;,&quot;useGrouping&quot;:&quot;no&quot;,&quot;decimalSymbol&quot;:&quot;.&quot;,&quot;counterSuffix&quot;:&quot;+&quot;}\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-content\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-number\">\n\t\t\t\t<span class=\"bdt-count-this\" id=\"bdt-ep-advanced-counter-data-e14dc78\" >\n\t\t\t\t\t62\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p\t\t\t\t\t\tclass=\"bdt-ep-advanced-counter-text\">\n\t\t\t\t\t\tLucr\u0103m cu \u021b\u0103ri\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f2eccbb\" data-id=\"f2eccbb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36d069c elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-bdt-advanced-counter\" data-id=\"36d069c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"bdt-advanced-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-counter\" data-settings=\"{&quot;id&quot;:&quot;bdt-ep-advanced-counter-data-36d069c&quot;,&quot;countStart&quot;:1,&quot;countNumber&quot;:1,&quot;language&quot;:[&quot;0&quot;,&quot;1&quot;,&quot;2&quot;,&quot;3&quot;,&quot;4&quot;,&quot;5&quot;,&quot;6&quot;,&quot;7&quot;,&quot;8&quot;,&quot;9&quot;],&quot;duration&quot;:&quot;2&quot;,&quot;useEasing&quot;:&quot;yes&quot;,&quot;useGrouping&quot;:&quot;no&quot;,&quot;decimalSymbol&quot;:&quot;.&quot;,&quot;counterSuffix&quot;:&quot;:200&quot;}\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-content\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-number\">\n\t\t\t\t<span class=\"bdt-count-this\" id=\"bdt-ep-advanced-counter-data-36d069c\" >\n\t\t\t\t\t1\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p\t\t\t\t\t\tclass=\"bdt-ep-advanced-counter-text\">\n\t\t\t\t\t\tP\u00e2rghie\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-af29a40\" data-id=\"af29a40\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9bf74b elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-bdt-advanced-counter\" data-id=\"b9bf74b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"bdt-advanced-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-counter\" data-settings=\"{&quot;id&quot;:&quot;bdt-ep-advanced-counter-data-b9bf74b&quot;,&quot;countStart&quot;:1,&quot;countNumber&quot;:500,&quot;language&quot;:[&quot;0&quot;,&quot;1&quot;,&quot;2&quot;,&quot;3&quot;,&quot;4&quot;,&quot;5&quot;,&quot;6&quot;,&quot;7&quot;,&quot;8&quot;,&quot;9&quot;],&quot;duration&quot;:&quot;2&quot;,&quot;useEasing&quot;:&quot;yes&quot;,&quot;useGrouping&quot;:&quot;no&quot;,&quot;decimalSymbol&quot;:&quot;.&quot;,&quot;counterSuffix&quot;:&quot;+&quot;}\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-content\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-number\">\n\t\t\t\t<span class=\"bdt-count-this\" id=\"bdt-ep-advanced-counter-data-b9bf74b\" >\n\t\t\t\t\t500\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p\t\t\t\t\t\tclass=\"bdt-ep-advanced-counter-text\">\n\t\t\t\t\t\tActive comerciale\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-cd4f795 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd4f795\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c00344b\" data-id=\"c00344b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8aa228 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"e8aa228\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Ce atrage traderii c\u0103tre Eral Capital?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b49ac8f elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b49ac8f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\tEral Capital atrage traderii cu abordarea sa inovatoare \u0219i ofertele moderne. Lucr\u0103m constant pentru a \u00eembun\u0103t\u0103\u021bi condi\u021biile \u0219i pentru a oferi cele mai avansate solu\u021bii care s\u0103 inspire investitorii s\u0103 ne aleag\u0103. Compania noastr\u0103 se str\u0103duie\u0219te s\u0103 creeze un mediu \u00een care fiecare utilizator \u00ee\u0219i poate atinge poten\u021bialul maxim.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-63a85ec\" data-id=\"63a85ec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be67a19 premium-floating-effects-yes elementor-invisible elementor-widget elementor-widget-image\" data-id=\"be67a19\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300,&quot;premium_fe_translate_switcher&quot;:&quot;yes&quot;,&quot;premium_fe_Xtranslate&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;from&quot;:0,&quot;to&quot;:0}},&quot;premium_fe_Ytranslate&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;from&quot;:0,&quot;to&quot;:32}},&quot;premium_fe_Xtranslate_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;premium_fe_Xtranslate_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;premium_fe_Ytranslate_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;premium_fe_Ytranslate_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;premium_fe_trans_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1000,&quot;sizes&quot;:[]},&quot;premium_fe_trans_delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;premium_fe_direction&quot;:&quot;alternate&quot;,&quot;premium_fe_loop&quot;:&quot;default&quot;,&quot;premium_fe_easing&quot;:&quot;easeInOutSine&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"612\" height=\"670\" src=\"https:\/\/eralcapital.ltd\/wp-content\/uploads\/about1-1.png\" class=\"attachment-full size-full wp-image-1614\" alt=\"\" srcset=\"https:\/\/eralcapital.ltd\/wp-content\/uploads\/about1-1.png 612w, https:\/\/eralcapital.ltd\/wp-content\/uploads\/about1-1-274x300.png 274w, https:\/\/eralcapital.ltd\/wp-content\/uploads\/about1-1-137x150.png 137w, https:\/\/eralcapital.ltd\/wp-content\/uploads\/about1-1-594x650.png 594w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2620890\" data-id=\"2620890\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dee898a elementor-invisible elementor-widget elementor-widget-image\" data-id=\"dee898a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"612\" height=\"672\" src=\"https:\/\/eralcapital.ltd\/wp-content\/uploads\/about-1-2.png\" class=\"attachment-full size-full wp-image-1615\" alt=\"\" srcset=\"https:\/\/eralcapital.ltd\/wp-content\/uploads\/about-1-2.png 612w, https:\/\/eralcapital.ltd\/wp-content\/uploads\/about-1-2-273x300.png 273w, https:\/\/eralcapital.ltd\/wp-content\/uploads\/about-1-2-137x150.png 137w, https:\/\/eralcapital.ltd\/wp-content\/uploads\/about-1-2-592x650.png 592w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d41476b elementor-invisible elementor-widget elementor-widget-image\" data-id=\"d41476b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"612\" height=\"378\" src=\"https:\/\/eralcapital.ltd\/wp-content\/uploads\/about-3.png\" class=\"attachment-full size-full wp-image-1403\" alt=\"\" srcset=\"https:\/\/eralcapital.ltd\/wp-content\/uploads\/about-3.png 612w, https:\/\/eralcapital.ltd\/wp-content\/uploads\/about-3-300x185.png 300w, https:\/\/eralcapital.ltd\/wp-content\/uploads\/about-3-150x93.png 150w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-edac9ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"edac9ae\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b2ee31f\" data-id=\"b2ee31f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fff80b7 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fff80b7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Capabilit\u0103\u021bile noastre<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-47640da elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47640da\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c2459c9\" data-id=\"c2459c9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6730888 bdt-icon-type-icon elementor-position-top bdt-icon-effect-none elementor-invisible elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"6730888\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"&#x428;&#x430;&#x440;_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 40 40\" style=\"enable-background:new 0 0 40 40;\" xml:space=\"preserve\"><style type=\"text\/css\">\t.st0{fill-rule:evenodd;clip-rule:evenodd;fill:#CB8900;}<\/style><g id=\"Artboard461\">\t<path class=\"st0\" d=\"M9.4,16.4L8,14.9c-0.2-0.2-0.2-0.7,0-0.9c0.2-0.2,0.7-0.2,0.9,0l0.2,0.2v-2.8c0-0.4,0.4-0.7,0.7-0.7  s0.7,0.4,0.7,0.7v2.8l0.2-0.2c0.2-0.2,0.7-0.2,0.9,0s0.2,0.7,0,0.9l-1.4,1.4C10.1,16.7,9.6,16.7,9.4,16.4z M4.4,17.8L3,16.4  c-0.2-0.2-0.2-0.7,0-0.9s0.7-0.2,0.9,0l0.2,0.2V9.7C4.2,9.4,4.6,9,4.9,9s0.7,0.4,0.7,0.7v6l0.2-0.4c0.2-0.2,0.7-0.2,0.9,0  c0.2,0.2,0.2,0.7,0,0.9l-1.4,1.4C5.1,18,4.8,18,4.4,17.8L4.4,17.8z M30.4,27.7l-0.2,0.2c-0.2,0.2-0.7,0.2-0.9,0  c-0.2-0.2-0.2-0.7,0-0.9l1.4-1.4c0.2-0.2,0.7-0.2,0.9,0L33,27c0.2,0.2,0.2,0.7,0,0.9c-0.2,0.2-0.7,0.2-0.9,0l-0.2-0.2v2.9  c0,0.4-0.4,0.7-0.7,0.7s-0.7-0.4-0.7-0.7V27.7z M35.2,26.4L35,26.6c-0.2,0.2-0.7,0.2-0.9,0c-0.2-0.2-0.2-0.7,0-0.9l1.4-1.4  c0.2-0.2,0.7-0.2,0.9,0l1.4,1.4c0.2,0.2,0.2,0.7,0,0.9c-0.2,0.2-0.7,0.2-0.9,0l-0.2-0.2v6c0,0.4-0.4,0.7-0.7,0.7s-0.7-0.4-0.7-0.7  V26.4z M20.8,30.6c2,2.6,4.5,7.4,3.9,8.4c-0.8,1.3-11,1.3-11.7,0c-0.4-0.6,0.5-2.7,1.7-4.8L20.8,30.6z M18.9,33  c-0.8,0-1.4,0.7-1.4,1.4s0.7,1.4,1.4,1.4c0.8,0,1.4-0.7,1.4-1.4S19.8,33,18.9,33L18.9,33z M34.7,21.1L4.3,38.6l-1.2-2l30.4-17.6  L34.7,21.1z M29.4,6.7c1.4,1.5,2.5,2.8,3.2,4c2.6,4.2-0.9,8.7-5.5,8.7c-4.7,0.1-8.3-4.1-5.9-8.6c0.7-1.2,1.7-2.6,3.1-4.1  c0.1,0,0.4,0.1,0.5,0l4.4-0.1C29.1,6.8,29.3,6.7,29.4,6.7L29.4,6.7z M27,14.7c-0.5,0-0.9-0.2-1.1-0.6c-0.1-0.4-0.5-0.6-0.8-0.5  c-0.4,0.1-0.6,0.5-0.5,0.8c0.2,0.8,0.9,1.4,1.7,1.5v0.1c0,0.4,0.4,0.7,0.7,0.7c0.4,0,0.7-0.4,0.7-0.7V16c0.9-0.2,1.8-0.9,1.7-2l0,0  c-0.1-1.2-1.3-1.7-2.2-1.8l0,0c-0.2,0-0.5-0.1-0.6-0.1c-0.1-0.1-0.4-0.2-0.4-0.4c0-0.2,0.2-0.5,0.5-0.6c0.1,0,0.2-0.1,0.4-0.1h0.1  c0.4,0,0.7,0.1,0.9,0.6c0.1,0.4,0.6,0.5,0.8,0.4c0.4-0.1,0.5-0.6,0.4-0.8c-0.4-0.7-0.8-1.2-1.5-1.3V9.7C27.7,9.4,27.3,9,27,9  c-0.4,0-0.7,0.4-0.7,0.7v0.1c-0.1,0-0.1,0-0.2,0.1c-0.8,0.1-1.3,0.7-1.3,1.7l0,0c0.1,1.2,1.1,1.7,2.1,1.8c0.2,0,0.5,0.1,0.7,0.2  c0.2,0.1,0.4,0.2,0.5,0.5c0,0.2-0.1,0.4-0.2,0.5C27.4,14.6,27.2,14.7,27,14.7L27,14.7L27,14.7z M24.7,3.5l-0.9-0.9  c-0.4-0.4-0.4-1.1,0-1.4C24.1,0.8,24.6,0.8,25,1c0.1,0.1,0.4,0.1,0.5,0.1c0.1-0.1,0.2-0.2,0.4-0.4C25.9,0.3,26.2,0,26.7,0  c0.5,0,0.8,0.4,0.9,0.7c0,0.1,0.1,0.2,0.4,0.4c0.1,0.1,0.4,0,0.5,0c0.4-0.2,0.9-0.2,1.3,0.1s0.4,1.1,0,1.4l-0.9,0.9H24.7z   M24.6,5.5c-0.1,0-0.4-0.1-0.4-0.2s0.1-0.4,0.2-0.4l4.4-0.1c0.1,0,0.4,0.1,0.4,0.2S29.1,5.4,29,5.4L24.6,5.5z M7.4,31  c-3.2,0-5.9-2.6-5.9-5.9c0-3.2,2.6-5.9,5.9-5.9c3.2,0,5.9,2.6,5.9,5.9S10.6,31,7.4,31z M6.7,21.7c-0.1,0-0.2,0.1-0.4,0.1  c-0.8,0.4-1.4,1.1-1.4,2l0,0c0.1,1.3,1.2,1.8,2.2,2l0,0c0.2,0,0.6,0.1,0.8,0.2c0.2,0.1,0.5,0.2,0.5,0.6c0,0.2-0.1,0.4-0.2,0.5  c-0.2,0.1-0.6,0.2-0.9,0.2c-0.6,0-1.2-0.2-1.3-0.8c-0.1-0.4-0.5-0.6-0.8-0.5c-0.4,0.1-0.6,0.5-0.5,0.8c0.2,0.9,0.9,1.5,1.9,1.8v0.2  c0,0.4,0.4,0.7,0.7,0.7c0.4,0,0.7-0.4,0.7-0.7v-0.2c1.1-0.2,2-0.9,1.9-2.2l0,0c-0.1-1.3-1.3-1.8-2.5-2c-0.2,0-0.5-0.1-0.7-0.2  c-0.2-0.1-0.4-0.2-0.4-0.5c0-0.4,0.2-0.6,0.5-0.7c0.6-0.2,1.3-0.1,1.5,0.6c0.1,0.4,0.6,0.5,0.8,0.4c0.4-0.1,0.5-0.6,0.4-0.8  c-0.1-0.7-0.7-1.2-1.4-1.4v-0.2c0-0.4-0.4-0.7-0.7-0.7c-0.4,0-0.7,0.4-0.7,0.7C6.7,21.4,6.7,21.7,6.7,21.7z M9.2,6.1  c0-0.4,0.4-0.7,0.7-0.7s0.7,0.4,0.7,0.7V9c0,0.4-0.4,0.7-0.7,0.7S9.2,9.4,9.2,9V6.1z M31.8,35.9c0,0.4-0.4,0.7-0.7,0.7  s-0.7-0.4-0.7-0.7V33c0-0.4,0.4-0.7,0.7-0.7c0.4,0,0.7,0.4,0.7,0.7V35.9z M34.3,2.4c0-0.4,0.4-0.7,0.7-0.7s0.7,0.4,0.7,0.7v1.4  c0,0.4-0.4,0.7-0.7,0.7c-0.4,0-0.7-0.4-0.7-0.7V2.4z M37.8,4.6c0.4,0,0.7,0.4,0.7,0.7c0,0.4-0.4,0.7-0.7,0.7h-1.4  c-0.4,0-0.7-0.4-0.7-0.7c0-0.4,0.4-0.7,0.7-0.7H37.8z M35.7,8.1c0,0.4-0.4,0.7-0.7,0.7s-0.7-0.4-0.7-0.7V6.7C34.3,6.3,34.6,6,35,6  c0.4,0,0.7,0.4,0.7,0.7V8.1z M32.1,6c-0.4,0-0.7-0.4-0.7-0.7c0-0.4,0.4-0.7,0.7-0.7h1.4c0.4,0,0.7,0.4,0.7,0.7  c0,0.4-0.4,0.7-0.7,0.7H32.1z M16.2,6.2c0-0.4,0.4-0.7,0.7-0.7c0.4,0,0.7,0.4,0.7,0.7v1.4c0,0.4-0.4,0.6-0.7,0.6s-0.7-0.4-0.7-0.7  C16.2,7.5,16.2,6.2,16.2,6.2z M19.8,8.3c0.4,0,0.7,0.4,0.7,0.7c0,0.4-0.4,0.7-0.7,0.7h-1.4c-0.4,0-0.7-0.4-0.7-0.7s0.4-0.7,0.7-0.7  H19.8z M17.6,11.9c0,0.4-0.4,0.7-0.7,0.7s-0.7-0.4-0.7-0.7v-1.4c0-0.4,0.4-0.7,0.7-0.7s0.7,0.4,0.7,0.7V11.9z M14.1,9.7  c-0.4,0-0.7-0.4-0.7-0.7c0-0.4,0.4-0.7,0.7-0.7h1.4c0.4,0,0.7,0.4,0.7,0.7c0,0.4-0.4,0.7-0.7,0.7H14.1z\"><\/path><\/g><\/svg>\n\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h3 class=\"bdt-ep-advanced-icon-box-title\">\n\t\t\t\t<span >\n\t\t\t\t\tLevier de<br>la 1:1 la 1:200\t\t\t\t<\/span>\n\t\t\t<\/h3>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06edf23 bdt-icon-type-icon elementor-position-top bdt-icon-effect-none elementor-invisible elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"06edf23\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 40 40\" style=\"enable-background:new 0 0 40 40;\" xml:space=\"preserve\"><style type=\"text\/css\">\t.st0{fill-rule:evenodd;clip-rule:evenodd;fill:#CB8900;}<\/style><path class=\"st0\" d=\"M29.6,3.4c1,0,1.8,0.8,1.8,1.8v10.7h-1.2V6.5c0-1.1-0.9-1.9-1.9-1.9H24V3.4L29.6,3.4z M33.4,28.1 c0.1,0.3,0,0.7-0.4,0.9c-0.3,0.1-0.7,0-0.9-0.4c-0.2-0.5-0.8-0.7-1.3-0.6c-0.4,0.1-0.7,0.3-0.7,0.7c0,0.5,0.7,0.6,1,0.7 c1.2,0.2,2.3,0.7,2.3,2.1c0,1.1-0.8,1.7-1.8,1.9v0.2c0,0.4-0.3,0.7-0.7,0.7c-0.4,0-0.7-0.3-0.7-0.7v-0.2c-0.9-0.2-1.5-0.8-1.8-1.7 c-0.1-0.4,0.1-0.7,0.5-0.8s0.7,0.1,0.8,0.5c0.1,0.5,0.7,0.7,1.2,0.7c0.4,0,1.1-0.2,1.1-0.6c0-0.6-0.8-0.7-1.2-0.8 c-1.1-0.2-2.1-0.7-2.2-1.9c0-1,0.7-1.8,1.6-2v-0.2c0-0.4,0.3-0.7,0.7-0.7c0.4,0,0.7,0.3,0.7,0.7v0.2C32.4,26.9,33,27.3,33.4,28.1 L33.4,28.1z M37.1,17.2c0,0,0.1,0.1,0.1,0.1l2.6,2.6c0,0,0.1,0.1,0.1,0.1h-2.6c-0.1,0-0.2-0.1-0.2-0.2L37.1,17.2L37.1,17.2z  M37.3,21.4c-0.9,0-1.6-0.7-1.6-1.6v-2.6h-13c-0.3,0-0.5,0.2-0.5,0.5v21.9c0,0.3,0.2,0.5,0.5,0.5h16.7c0.3,0,0.5-0.2,0.5-0.5V21.4 L37.3,21.4L37.3,21.4z M31.1,35.6c-3.1,0-5.6-2.5-5.6-5.6c0-3.1,2.5-5.6,5.6-5.6s5.6,2.5,5.6,5.6C36.7,33.1,34.2,35.6,31.1,35.6z  M7.8,28.2h3c0.5,0,1,0.4,1,0.9l-1.6,1.4l-1-1c-0.3-0.3-0.7-0.3-0.9,0c-0.3,0.3-0.3,0.7,0,0.9L9.8,32c0.3,0.3,0.7,0.3,0.9,0l1.1-1 v1.3c0,0.5-0.4,1-1,1h-3c-0.5,0-1-0.4-1-1v-3C6.8,28.7,7.3,28.2,7.8,28.2L7.8,28.2z M7.8,19.7h3c0.5,0,1,0.4,1,0.9l-1.6,1.4l-1-1 c-0.3-0.3-0.7-0.3-0.9,0s-0.3,0.7,0,0.9l1.5,1.5c0.3,0.3,0.7,0.3,0.9,0l1.1-1v1.3c0,0.5-0.4,1-1,1h-3c-0.5,0-1-0.4-1-1v-3 C6.8,20.2,7.3,19.7,7.8,19.7z M7.8,11.3h3c0.5,0,1,0.4,1,0.9l-1.6,1.4l-1-1c-0.3-0.3-0.7-0.3-0.9,0s-0.3,0.7,0,0.9L9.8,15 c0.3,0.3,0.7,0.3,0.9,0l1.1-1v1.3c0,0.5-0.4,1-1,1h-3c-0.5,0-1-0.4-1-1v-3C6.8,11.7,7.3,11.3,7.8,11.3L7.8,11.3z M22.3,2.3h-3.5 C18.4,1,17.2,0,15.8,0s-2.6,1-3,2.3H9.2C9,2.3,8.8,2.5,8.8,2.7v3.8C8.8,6.8,9,7,9.2,7h13c0.2,0,0.4-0.2,0.4-0.4V2.7 C22.7,2.5,22.5,2.3,22.3,2.3z M15.8,3.5c-0.4,0-0.8-0.4-0.8-0.8c0-0.4,0.4-0.8,0.8-0.8c0.4,0,0.8,0.4,0.8,0.8 C16.6,3.1,16.2,3.5,15.8,3.5z M28.3,5.9H24v0.7c0,1-0.8,1.8-1.8,1.8h-13c-1,0-1.8-0.8-1.8-1.8V5.9H3.2c-0.3,0-0.6,0.3-0.6,0.6v30.4 c0,0.3,0.3,0.6,0.6,0.6H21v-4.3h-4.8c-0.4,0-0.7-0.3-0.7-0.7c0-0.4,0.3-0.7,0.7-0.7H21v-2.3h-4.8c-0.4,0-0.7-0.3-0.7-0.7 c0-0.4,0.3-0.7,0.7-0.7H21v-3.6h-4.8c-0.4,0-0.7-0.3-0.7-0.7c0-0.4,0.3-0.7,0.7-0.7H21v-2.3h-4.8c-0.4,0-0.7-0.3-0.7-0.7 c0-0.4,0.3-0.7,0.7-0.7H21v-2.1c0-0.6,0.3-1.1,0.7-1.4h-5.5c-0.4,0-0.7-0.3-0.7-0.7s0.3-0.7,0.7-0.7h8.5c0.4,0,0.7,0.3,0.7,0.7 c0,0.1,0,0.2-0.1,0.3h3.6V6.5C28.9,6.2,28.6,5.9,28.3,5.9L28.3,5.9z M14.3,28.7l-1.1,1v2.5c0,1.3-1,2.3-2.3,2.3h-3 c-1.3,0-2.3-1-2.3-2.3v-3c0-1.3,1-2.3,2.3-2.3h3c0.9,0,1.7,0.5,2.1,1.3l0.5-0.4c0.3-0.2,0.7-0.2,0.9,0 C14.6,28.1,14.6,28.5,14.3,28.7L14.3,28.7z M14.3,20.3l-1.1,1v2.5c0,1.3-1,2.3-2.3,2.3h-3c-1.3,0-2.3-1-2.3-2.3v-3 c0-1.3,1-2.3,2.3-2.3h3c0.9,0,1.7,0.5,2.1,1.3l0.5-0.4c0.3-0.2,0.7-0.2,0.9,0C14.6,19.6,14.6,20,14.3,20.3L14.3,20.3z M14.3,11.8 l-1.1,1v2.5c0,1.3-1,2.3-2.3,2.3h-3c-1.3,0-2.3-1-2.3-2.3v-3c0-1.3,1-2.3,2.3-2.3h3c0.9,0,1.7,0.5,2.1,1.3l0.5-0.4 c0.3-0.2,0.7-0.2,0.9,0C14.6,11.1,14.6,11.5,14.3,11.8L14.3,11.8z M24.7,12.6h-8.5c-0.4,0-0.7-0.3-0.7-0.7c0-0.4,0.3-0.7,0.7-0.7 h8.5c0.4,0,0.7,0.3,0.7,0.7C25.3,12.3,25,12.6,24.7,12.6z M21,38.8H3.2c-1.1,0-1.9-0.9-1.9-1.9V6.5c0-1.1,0.9-1.9,1.9-1.9h4.3V3.4 H1.9c-1,0-1.8,0.8-1.8,1.8v33c0,1,0.8,1.8,1.8,1.8H21c0-0.1-0.1-0.3-0.1-0.5V38.8z\"><\/path><\/svg>\n\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h3 class=\"bdt-ep-advanced-icon-box-title\">\n\t\t\t\t<span >\n\t\t\t\t\tExecutare<br>instantanee a comenzilor\t\t\t\t<\/span>\n\t\t\t<\/h3>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7ccdc97\" data-id=\"7ccdc97\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-269e753 bdt-icon-type-icon elementor-position-top bdt-icon-effect-none elementor-invisible elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"269e753\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 40 40\" style=\"enable-background:new 0 0 40 40;\" xml:space=\"preserve\"><style type=\"text\/css\">\t.st0{fill-rule:evenodd;clip-rule:evenodd;fill:#CB8900;}<\/style><path class=\"st0\" d=\"M22.3,4.5c-6.7,0-12.2,5.4-12.2,12c0,2.6,0.8,5,2.2,7c-1.3,1.2-2.5,2.5-3.8,3.7l-0.1-0.1 c-0.5-0.5-1.1-0.5-1.5,0l-6.6,6.5c-0.5,0.5-0.5,1.1,0,1.5l2.4,2.5c0.5,0.5,1.1,0.5,1.5,0l6.6-6.5c0.5-0.5,0.5-1.1,0-1.5l-0.1-0.1 c1.3-1.2,2.5-2.4,3.8-3.7c2.1,1.8,4.8,2.9,7.9,2.9c4,0,7.4-1.9,9.7-4.8h-0.7c-0.7,0-1.3-0.4-1.8-0.8c-1.8,2-4.4,3.3-7.3,3.3 c-5.3,0-9.7-4.4-9.7-9.7c-0.1-5.4,4.2-9.8,9.7-9.8c0.4,0,0.6,0,0.8,0c0.2-1.1,1.1-1.9,2.1-2.1C24.3,4.7,23.2,4.5,22.3,4.5L22.3,4.5z  M20.2,11.2l4.2-3.3c0-0.1,0-0.1,0-0.2c0-0.8,0.6-1.4,1.4-1.4c0.7,0,1.2,0.5,1.4,1.1L31,8.1c0.2-0.4,0.7-0.5,1.1-0.5 c0.2,0,0.4,0,0.5,0.1l4.4-3.9c0-0.1,0-0.2,0-0.4c0-0.8,0.6-1.4,1.4-1.4c0.8,0,1.4,0.6,1.4,1.4s-0.6,1.4-1.4,1.4 c-0.2,0-0.4,0-0.5-0.1l-4.4,3.9c0,0.1,0,0.2,0,0.4c0,0.8-0.6,1.4-1.4,1.4c-0.7,0-1.2-0.5-1.4-1.1l-3.8-0.8C26.7,8.9,26.2,9,25.8,9 c-0.2,0-0.5,0-0.6-0.1L21,12.2c0,0.1,0,0.1,0,0.2c0,0.8-0.6,1.4-1.4,1.4c-0.8,0-1.4-0.6-1.4-1.4s0.6-1.4,1.4-1.4 C19.8,11,20.1,11,20.2,11.2L20.2,11.2z M18.8,17.5h1.7c0.5,0,0.8,0.4,0.8,0.8v3.4c0,0.5-0.4,0.8-0.8,0.8h-1.7 c-0.5,0-0.8-0.4-0.8-0.8v-3.4C17.9,17.9,18.3,17.5,18.8,17.5L18.8,17.5z M37.5,7.4c-0.5,0-0.8,0.4-0.8,0.8v13.5 c0,0.5,0.4,0.8,0.8,0.8h1.7c0.5,0,0.8-0.4,0.8-0.8V8.2c0-0.5-0.4-0.8-0.8-0.8H37.5z M31.3,14.1h1.7c0.5,0,0.8,0.4,0.8,0.8v6.7 c0,0.5-0.4,0.8-0.8,0.8c-0.6,0-1.2,0-1.7,0c-0.5,0-0.8-0.4-0.8-0.8c0-2.7,0-4.1,0-6.7C30.4,14.5,30.8,14.1,31.3,14.1z M25,11.7h1.7 c0.5,0,0.8,0.4,0.8,0.8v9.1c0,0.5-0.4,0.8-0.8,0.8H25c-0.5,0-0.8-0.4-0.8-0.8v-9.1C24.2,12.2,24.5,11.7,25,11.7z\"><\/path><\/svg>\n\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h3 class=\"bdt-ep-advanced-icon-box-title\">\n\t\t\t\t<span >\n\t\t\t\t\tSemnale de analiz\u0103<br>\u0219i tranzac\u021bionare\t\t\t\t<\/span>\n\t\t\t<\/h3>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b206bdd bdt-icon-type-icon elementor-position-top bdt-icon-effect-none elementor-invisible elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"b206bdd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 40 40\" style=\"enable-background:new 0 0 40 40;\" xml:space=\"preserve\"><style type=\"text\/css\">\t.st0{fill-rule:evenodd;clip-rule:evenodd;fill:#CB8900;}<\/style><path class=\"st0\" d=\"M22.9,22.4c-0.6,0-1.1,0.5-1.1,1.1s0.5,1.1,1.1,1.1c0.6,0,1.1-0.5,1.1-1.1C23.8,22.9,23.4,22.4,22.9,22.4z  M17.1,15.5c-0.6,0-1.1,0.5-1.1,1.1s0.5,1.1,1.1,1.1s1.1-0.5,1.1-1.1C18.1,16,17.6,15.5,17.1,15.5L17.1,15.5z M20,10.6 c-5.1,0-9.4,4.2-9.4,9.4s4.2,9.4,9.4,9.4s9.4-4.2,9.4-9.4S25.1,10.6,20,10.6L20,10.6z M14.7,16.6c0-1.3,1.1-2.3,2.3-2.3 s2.3,1.1,2.3,2.3s-1.1,2.3-2.3,2.3S14.7,17.9,14.7,16.6z M17.1,25.3c-0.2,0.4-0.6,0.4-0.9,0.1c-0.4-0.2-0.4-0.6-0.1-0.9l7.1-9.8 c0.2-0.4,0.6-0.4,0.9-0.1s0.4,0.6,0.1,0.9L17.1,25.3z M22.9,25.7c-1.3,0-2.3-1.1-2.3-2.3s1.1-2.3,2.3-2.3s2.3,1.1,2.3,2.3 S24.2,25.7,22.9,25.7L22.9,25.7z M36.6,16c-0.5-1.8-1.2-3.4-2.1-4.9l1.4-3.3L32,4l-3.3,1.4c-1.5-0.9-3.2-1.6-4.9-2.1l-1.2-3.2h-5.4 L16,3.4c-1.8,0.5-3.4,1.2-4.9,2.1L7.8,4.1L4.1,7.8l1.4,3.3c-0.9,1.5-1.6,3.2-2.1,4.9l-3.3,1.3v5.4L3.4,24c0.5,1.8,1.2,3.4,2.1,4.9 l-1.4,3.3L7.9,36l3.3-1.4c1.5,0.9,3.2,1.6,4.9,2.1l1.3,3.3h5.4l1.3-3.3c1.8-0.5,3.4-1.2,4.9-2.1l3.3,1.4l3.9-3.9l-1.4-3.3 c0.9-1.5,1.6-3.2,2.1-4.9l3.3-1.3v-5.4L36.6,16z M20,32.3c-6.8,0-12.3-5.5-12.3-12.3S13.2,7.7,20,7.7S32.3,13.2,32.3,20 S26.8,32.3,20,32.3z\"><\/path><\/svg>\n\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h3 class=\"bdt-ep-advanced-icon-box-title\">\n\t\t\t\t<span >\n\t\t\t\t\tComisioane<br>\u0219i spreaduri minime\t\t\t\t<\/span>\n\t\t\t<\/h3>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b4c8f63\" data-id=\"b4c8f63\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1b2c8f bdt-icon-type-icon elementor-position-top bdt-icon-effect-none elementor-invisible elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"c1b2c8f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 40 40\" style=\"enable-background:new 0 0 40 40;\" xml:space=\"preserve\"><style type=\"text\/css\">\t.st0{fill-rule:evenodd;clip-rule:evenodd;fill:#CB8900;}<\/style><path class=\"st0\" d=\"M2.6,11.6c0.4,0,0.7,0.2,0.7,0.7c0,0.5-0.4,0.6-0.7,0.6H0.7c-0.5,0-0.7-0.4-0.7-0.7c0-0.4,0.2-0.7,0.7-0.7h1.9 V11.6z M35.5,6.6H16.7c-0.2,0.7-0.8,1.3-1.5,1.5v4.5c0.7,0.2,1.3,0.8,1.5,1.5h18.8c0.2-0.7,0.8-1.3,1.5-1.5V8.1 C36.2,7.9,35.6,7.3,35.5,6.6z M20.6,11.1h-2.5c-0.4,0-0.7-0.2-0.7-0.7c0-0.5,0.2-0.7,0.7-0.7h2.5c0.4,0,0.7,0.2,0.7,0.7 C21.3,10.8,20.9,11.1,20.6,11.1z M26.7,13.1L26.7,13.1c0,0.4-0.2,0.7-0.7,0.7c-0.4,0-0.7-0.2-0.7-0.7l0,0c-0.7-0.2-1.2-0.7-1.3-1.3 c-0.1-0.4,0.1-0.7,0.5-0.8c0.4-0.1,0.7,0.1,0.8,0.5c0.1,0.4,0.5,0.5,0.7,0.5h0.1c0.1,0,0.5-0.1,0.5-0.4l0,0c0-0.4-0.6-0.4-0.8-0.5 c-0.8-0.1-1.6-0.6-1.8-1.5c0-0.8,0.5-1.4,1.2-1.6l0,0c0-0.4,0.2-0.7,0.7-0.7s0.7,0.2,0.7,0.7l0,0c0.5,0.1,0.9,0.5,1.2,1.1 c0.1,0.4,0,0.7-0.4,0.8c-0.4,0.1-0.7,0-0.8-0.4c-0.1-0.4-0.5-0.5-0.8-0.4c-0.2,0-0.4,0.1-0.4,0.4s0.5,0.4,0.7,0.4 c0.9,0.1,1.8,0.6,1.9,1.5v0.1C28.1,12.2,27.5,12.8,26.7,13.1L26.7,13.1z M34,11.1h-2.5c-0.4,0-0.7-0.2-0.7-0.7 c0-0.5,0.2-0.7,0.7-0.7H34c0.4,0,0.7,0.2,0.7,0.7C34.7,10.8,34.3,11.1,34,11.1z M39.2,3.5c-10.7,0-21.3,0-32,0 c-0.4,0-0.6,0.4-0.6,0.7s0.2,0.7,0.7,0.7h4.9v6.7H5.4c-0.4,0-0.7,0.2-0.7,0.6s0.4,0.7,0.7,0.7h6.8V16H10c-0.4,0-0.7,0.2-0.7,0.7 c0,0.4,0.2,0.7,0.7,0.7h29.2c0.5,0,0.8-0.4,0.8-0.8V4.4C40,3.9,39.5,3.5,39.2,3.5L39.2,3.5z M38.3,13.2c0,0.4-0.2,0.7-0.7,0.7 c-0.6,0-0.9,0.5-0.9,1.1c0,0.4-0.2,0.7-0.7,0.7H16.1c-0.4,0-0.7-0.2-0.7-0.7c0-0.6-0.5-1.1-0.9-1.1c-0.4,0-0.7-0.2-0.7-0.7V7.5 c0-0.4,0.2-0.7,0.7-0.7c0.6,0,0.9-0.5,0.9-1.1c0-0.4,0.2-0.7,0.7-0.7H36c0.4,0,0.7,0.2,0.7,0.7c0,0.6,0.5,1.1,0.9,1.1 c0.4,0,0.7,0.2,0.7,0.7V13.2L38.3,13.2z M7.3,15.9c0.4,0,0.7,0.2,0.7,0.7c0,0.4-0.2,0.7-0.7,0.7H3.9c-0.4,0-0.7-0.2-0.7-0.7 c0-0.4,0.2-0.7,0.7-0.7H7.3z M9.7,7.9c0.4,0,0.7,0.2,0.7,0.7c0,0.4-0.2,0.7-0.7,0.7H3.5c-0.4,0-0.7-0.2-0.7-0.7 c0-0.4,0.2-0.7,0.7-0.7H9.7z M4.6,3.5c0.4,0,0.7,0.2,0.7,0.7S5,4.8,4.6,4.8H0.7C0.2,4.8,0,4.6,0,4.2s0.2-0.7,0.7-0.7H4.6z  M22.8,25.6c0.8,0.1,1.5-0.1,1.9-1.1c0.2-0.8-0.4-1.5-1.1-1.9c-2.4-0.5-4.6-1.2-6.3-1.9c-2.6-0.9-3.3-1.2-5.8,0.4l-4.7,2.7l3.9,6.7 l0.6-0.4c0.1-0.1,0.4-0.1,0.5-0.1l10.1,2.7c1.5,0.4,2.4,0.1,3.6-0.6l13.9-8.6c0.5-0.2,0.7-0.9,0.6-1.6c0-0.6-0.4-1.1-0.8-1.3 c-0.7-0.4-2-0.2-4,0.8L27.5,26c-0.6,0.4-1.2,0.6-1.9,0.7c-1.9,0.4-4.7-0.6-6.5-1.1c-0.6-0.1-1.1-0.4-1.6-0.5 c-0.4-0.1-0.6-0.5-0.5-0.8s0.5-0.6,0.8-0.5C19.5,24.8,21.2,25.3,22.8,25.6L22.8,25.6z M10.8,33.6L4.7,22.8c-0.4-0.5-0.9-0.7-1.5-0.4 l-2.1,1.2c-0.5,0.4-0.7,0.9-0.4,1.5L6.8,36c0.4,0.5,0.9,0.7,1.5,0.4l2.1-1.2C10.9,34.8,11.2,34.1,10.8,33.6z M3.5,26 c-0.4,0.1-0.8-0.2-0.8-0.6c0-0.4,0.2-0.8,0.6-0.8c0.4-0.1,0.8,0.2,0.8,0.6C4.2,25.5,4,25.9,3.5,26z\"><\/path><\/svg>\n\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h3 class=\"bdt-ep-advanced-icon-box-title\">\n\t\t\t\t<span >\n\t\t\t\t\tRetragere rapid\u0103<br>\u0219i sigur\u0103 a fondurilor\t\t\t\t<\/span>\n\t\t\t<\/h3>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38860c9 bdt-icon-type-icon elementor-position-top bdt-icon-effect-none elementor-invisible elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"38860c9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"&#x428;&#x430;&#x440;_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 40 40\" style=\"enable-background:new 0 0 40 40;\" xml:space=\"preserve\"><style type=\"text\/css\">\t.st0{fill-rule:evenodd;clip-rule:evenodd;fill:#CB8900;}<\/style><path class=\"st0\" d=\"M20,23.2c-5.3,0-9.5-4.3-9.5-9.5s4.3-9.5,9.5-9.5c5.3,0,9.5,4.3,9.5,9.5c0,1.4-0.3,2.8-0.9,4 c-0.9,0.1-2,0.1-3.2,0c-0.3-0.5-0.8-0.8-1.4-0.8c-0.8,0-1.5,0.7-1.5,1.5c0,0.8,0.7,1.5,1.5,1.5c0.6,0,1.2-0.4,1.4-0.9 c0.8,0,1.6,0,2.4,0C26.2,21.5,23.3,23.2,20,23.2c1.3,0,2.5,0.1,3.7,0.4L20,26.4l-3.7-2.9C17.5,23.3,18.7,23.2,20,23.2L20,23.2z  M32,16.1h-0.7v-4.8h0.9C30.5,1.9,20-1,13.3,3.2c-2.6,1.6-4.6,4.3-5.4,8.1h0.4c0.1,0,0.2,0,0.3,0.1c0.1,0.1,0.1,0.2,0.1,0.3v4 c0,0.1,0,0.2-0.1,0.3c-0.1,0.1-0.2,0.1-0.3,0.1H6c-0.5,0-0.9-0.4-0.9-0.9v-3c0-0.5,0.4-0.9,0.9-0.9h0.5c0.8-4.3,3.1-7.3,6-9.2 c7.5-4.7,19.3-1.4,21,9.2H34c0.5,0,0.9,0.4,0.9,0.9v3c0,0.5-0.4,0.9-0.9,0.9h-0.6c0,0.1,0,0.2,0,0.2c-0.4,1.1-1.3,1.8-2.5,2.2 c-0.7,0.2-1.6,0.4-2.5,0.5c0.3-0.4,0.5-0.9,0.7-1.4c0.2,0,0.4-0.1,0.6-0.1C30.7,17.3,31.5,16.8,32,16.1L32,16.1z M12,25 C12,25,12,25,12,25l3.8,6.9c0.1,0.2,0.3,0.3,0.5,0.3c0.2,0,0.4-0.1,0.6-0.2l0.4-0.5l-1.1,5.1c0,0.2,0,0.4,0.2,0.6l2.7,2.9H1.7 c-0.1,0-0.2-0.1-0.3-0.1c-0.1-0.1-0.1-0.2-0.1-0.3C2.2,33.1,6.3,27.6,12,25L12,25z M12.7,32.3c0-0.1-0.1-0.3-0.2-0.4 c-0.1-0.1-0.2-0.2-0.4-0.2H8.4c-0.1,0-0.3,0.1-0.4,0.2c-0.1,0.1-0.2,0.2-0.2,0.4v1.2c0,0.1,0.1,0.3,0.2,0.4C8.1,34,8.3,34,8.4,34 h3.7c0.1,0,0.3-0.1,0.4-0.2c0.1-0.1,0.2-0.2,0.2-0.4V32.3z M20.9,40l2.7-2.9c0.1-0.2,0.2-0.4,0.2-0.6l-1.1-5.1l0.4,0.5 c0.1,0.2,0.3,0.3,0.6,0.2c0.2,0,0.4-0.1,0.5-0.3L28,25c0,0,0,0,0-0.1c5.7,2.7,9.8,8.1,10.7,14.6c0,0.1,0,0.2-0.1,0.3 c-0.1,0.1-0.2,0.1-0.3,0.1C35.5,40,20.9,40,20.9,40L20.9,40z M19.1,29.3l0.9-1l0.9,1l1.5,7.1L20,39l-2.3-2.6L19.1,29.3z M18,28.6 C18,28.6,18,28.6,18,28.6l-1.5,1.8l-3-5.3c0.6-0.2,1.2-0.4,1.8-0.6l3.7,2.9L18,28.6z M22,28.6C22,28.6,22,28.6,22,28.6l-1-1.2 l3.7-2.9c0.6,0.2,1.2,0.4,1.8,0.6l-3,5.3L22,28.6z\"><\/path><\/svg>\n\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h3 class=\"bdt-ep-advanced-icon-box-title\">\n\t\t\t\t<span >\n\t\t\t\t\tServiciu<br>deasisten\u021b\u0103 avansat\t\t\t\t<\/span>\n\t\t\t<\/h3>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a67d100 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a67d100\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-57288d1\" data-id=\"57288d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc61d56 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"fc61d56\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"929\" height=\"708\" src=\"https:\/\/eralcapital.ltd\/wp-content\/uploads\/about-4.png\" class=\"attachment-full size-full wp-image-1412\" alt=\"\" srcset=\"https:\/\/eralcapital.ltd\/wp-content\/uploads\/about-4.png 929w, https:\/\/eralcapital.ltd\/wp-content\/uploads\/about-4-300x229.png 300w, https:\/\/eralcapital.ltd\/wp-content\/uploads\/about-4-150x114.png 150w, https:\/\/eralcapital.ltd\/wp-content\/uploads\/about-4-768x585.png 768w, https:\/\/eralcapital.ltd\/wp-content\/uploads\/about-4-650x495.png 650w\" sizes=\"(max-width: 929px) 100vw, 929px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5c75355\" data-id=\"5c75355\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65b49eb elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"65b49eb\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tranzac\u021bionare de succes cu Eral Capital<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68251ec elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"68251ec\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Compania noastr\u0103 se str\u0103duie\u0219te s\u0103 fie partenerul dvs. de \u00eencredere \u00een atingerea obiectivelor dvs. financiare. Nu oferim doar acces la pie\u021bele globale, cre\u0103m un mediu \u00een care pute\u021bi cre\u0219te \u0219i reu\u0219i. Echipa noastr\u0103 acord\u0103 aten\u021bie fiec\u0103rui client, oferind cel mai \u00eenalt nivel de servicii \u0219i suport \u00een fiecare etap\u0103 a c\u0103l\u0103toriei dvs. de tranzac\u021bionare.<\/p>\n\n<p>Recunoa\u0219tem c\u0103 fiecare comerciant este unic, de aceea oferim o gam\u0103 larg\u0103 de instrumente \u0219i resurse pentru a se potrivi unei variet\u0103\u021bi de nevoi \u0219i stiluri de tranzac\u021bionare. Platforma noastr\u0103 este conceput\u0103 folosind tehnologie avansat\u0103, oferind acces instantaneu la datele pie\u021bei \u0219i execu\u021bie rapid\u0103 a comenzilor.<\/p>\n\n<p>Al\u0103tur\u00e2ndu-v\u0103 la Eral Capital, nu numai c\u0103 ve\u021bi ob\u021bine acces la bursele globale, ci \u0219i o echip\u0103 de exper\u021bi gata s\u0103 v\u0103 sprijine \u00een fiecare decizie de tranzac\u021bionare pe care o lua\u021bi. Ne str\u0103duim s\u0103 fim partenerul dvs. \u0219i suntem gata s\u0103 v\u0103 ajut\u0103m s\u0103 v\u0103 atinge\u021bi aspira\u021biile.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-92548bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92548bb\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eedcd5a\" data-id=\"eedcd5a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b92559a elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b92559a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Scufunda\u021bi-v\u0103 \u00een lumea investi\u021biilor cu Eral Capital<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af54d4c elementor-widget elementor-widget-spacer\" data-id=\"af54d4c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95994e6 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"95994e6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tAvem o varietate de active, instrumente analitice \u0219i analiz\u0103 preg\u0103tit\u0103, ca s\u0103 v\u0103 pute\u021bi dezvolta cu succes\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22d3a82 elementor-widget elementor-widget-spacer\" data-id=\"22d3a82\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8da44ed elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"8da44ed\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/ro\/sign-up\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Al\u0103tura\u021bi-v\u0103<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b879b7 elementor-widget elementor-widget-spacer\" data-id=\"2b879b7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>1 Clien\u021bi activi 62 Lucr\u0103m cu \u021b\u0103ri 1 P\u00e2rghie 500 Active comerciale [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/eralcapital.ltd\/ro\/wp-json\/wp\/v2\/pages\/2251"}],"collection":[{"href":"https:\/\/eralcapital.ltd\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eralcapital.ltd\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eralcapital.ltd\/ro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eralcapital.ltd\/ro\/wp-json\/wp\/v2\/comments?post=2251"}],"version-history":[{"count":6,"href":"https:\/\/eralcapital.ltd\/ro\/wp-json\/wp\/v2\/pages\/2251\/revisions"}],"predecessor-version":[{"id":2320,"href":"https:\/\/eralcapital.ltd\/ro\/wp-json\/wp\/v2\/pages\/2251\/revisions\/2320"}],"wp:attachment":[{"href":"https:\/\/eralcapital.ltd\/ro\/wp-json\/wp\/v2\/media?parent=2251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}