{"id":934,"date":"2024-05-22T10:47:57","date_gmt":"2024-05-22T10:47:57","guid":{"rendered":"https:\/\/eralcapital.ltd\/?page_id=934"},"modified":"2024-09-09T12:20:17","modified_gmt":"2024-09-09T12:20:17","slug":"technical-analysis","status":"publish","type":"page","link":"https:\/\/eralcapital.ltd\/en\/technical-analysis","title":{"rendered":"Technical analysis"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"934\" class=\"elementor elementor-934\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-669e2ba e-grid e-con-boxed e-con e-parent\" data-id=\"669e2ba\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78344e8 elementor-widget elementor-widget-html\" data-id=\"78344e8\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n<div class=\"tradingview-widget-container tvwidget\">\r\n  <div class=\"tradingview-widget-container__widget\"><\/div>\r\n  <script type=\"text\/javascript\" src=\"https:\/\/s3.tradingview.com\/external-embedding\/embed-widget-technical-analysis.js\" async>\r\n  {\r\n  \"interval\": \"1m\",\r\n  \"width\": \"100%\",\r\n  \"isTransparent\": false,\r\n  \"height\": \"380\",\r\n  \"symbol\": \"NASDAQ:AAPL\",\r\n  \"showIntervalTabs\": true,\r\n  \"displayMode\": \"single\",\r\n  \"locale\": \"en\",\r\n  \"colorTheme\": \"light\"\r\n}\r\n  <\/script>\r\n<\/div>\r\n\r\n<a class=\"brand-label\"><img decoding=\"async\" src=\"https:\/\/eralcapital.ltd\/wp-content\/uploads\/favicon1-1.svg\"\/><\/a>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49c2bd8 elementor-widget elementor-widget-html\" data-id=\"49c2bd8\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n<div class=\"tradingview-widget-container tvwidget\">\r\n  <div class=\"tradingview-widget-container__widget\"><\/div>\r\n  <script type=\"text\/javascript\" src=\"https:\/\/s3.tradingview.com\/external-embedding\/embed-widget-technical-analysis.js\" async>\r\n  {\r\n  \"interval\": \"1m\",\r\n  \"width\": \"100%\",\r\n  \"isTransparent\": false,\r\n  \"height\": \"380\",\r\n \"symbol\": \"NASDAQ:AMZN\",\r\n  \"showIntervalTabs\": true,\r\n  \"displayMode\": \"single\",\r\n  \"locale\": \"en\",\r\n  \"colorTheme\": \"light\"\r\n}\r\n  <\/script>\r\n<\/div>\r\n\r\n<a class=\"brand-label\"><img decoding=\"async\" src=\"https:\/\/eralcapital.ltd\/wp-content\/uploads\/favicon1-1.svg\"\/><\/a>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74b0e5d elementor-widget elementor-widget-html\" data-id=\"74b0e5d\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n<div class=\"tradingview-widget-container tvwidget\">\r\n  <div class=\"tradingview-widget-container__widget\"><\/div>\r\n  <script type=\"text\/javascript\" src=\"https:\/\/s3.tradingview.com\/external-embedding\/embed-widget-technical-analysis.js\" async>\r\n  {\r\n  \"interval\": \"1m\",\r\n  \"width\": \"100%\",\r\n  \"isTransparent\": false,\r\n  \"height\": \"380\",\r\n  \"symbol\": \"OANDA:EURUSD\",\r\n  \"showIntervalTabs\": true,\r\n  \"displayMode\": \"single\",\r\n  \"locale\": \"en\",\r\n  \"colorTheme\": \"light\"\r\n}\r\n  <\/script>\r\n<\/div>\r\n\r\n<a class=\"brand-label\"><img decoding=\"async\" src=\"https:\/\/eralcapital.ltd\/wp-content\/uploads\/favicon1-1.svg\"\/><\/a>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-734ee35 elementor-widget elementor-widget-html\" data-id=\"734ee35\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n<div class=\"tradingview-widget-container tvwidget\">\r\n  <div class=\"tradingview-widget-container__widget\"><\/div>\r\n  <script type=\"text\/javascript\" src=\"https:\/\/s3.tradingview.com\/external-embedding\/embed-widget-technical-analysis.js\" async>\r\n  {\r\n  \"interval\": \"1m\",\r\n  \"width\": \"100%\",\r\n  \"isTransparent\": false,\r\n  \"height\": \"380\",\r\n  \"symbol\": \"OANDA:GBPUSD\",\r\n  \"showIntervalTabs\": true,\r\n  \"displayMode\": \"single\",\r\n  \"locale\": \"en\",\r\n  \"colorTheme\": \"light\"\r\n}\r\n  <\/script>\r\n<\/div>\r\n\r\n<a class=\"brand-label\"><img decoding=\"async\" src=\"https:\/\/eralcapital.ltd\/wp-content\/uploads\/favicon1-1.svg\"\/><\/a>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1098938 elementor-widget elementor-widget-html\" data-id=\"1098938\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n<div class=\"tradingview-widget-container tvwidget\">\r\n  <div class=\"tradingview-widget-container__widget\"><\/div>\r\n  <script type=\"text\/javascript\" src=\"https:\/\/s3.tradingview.com\/external-embedding\/embed-widget-technical-analysis.js\" async>\r\n  {\r\n  \"interval\": \"1m\",\r\n  \"width\": \"100%\",\r\n  \"isTransparent\": false,\r\n  \"height\": \"380\",\r\n \"symbol\": \"COMEX:GC1!\",\r\n  \"showIntervalTabs\": true,\r\n  \"displayMode\": \"single\",\r\n  \"locale\": \"en\",\r\n  \"colorTheme\": \"light\"\r\n}\r\n  <\/script>\r\n<\/div>\r\n\r\n<a class=\"brand-label\"><img decoding=\"async\" src=\"https:\/\/eralcapital.ltd\/wp-content\/uploads\/favicon1-1.svg\"\/><\/a>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d3811d elementor-widget elementor-widget-html\" data-id=\"5d3811d\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n<div class=\"tradingview-widget-container tvwidget\">\r\n  <div class=\"tradingview-widget-container__widget\"><\/div>\r\n  <script type=\"text\/javascript\" src=\"https:\/\/s3.tradingview.com\/external-embedding\/embed-widget-technical-analysis.js\" async>\r\n  {\r\n  \"interval\": \"1m\",\r\n  \"width\": \"100%\",\r\n  \"isTransparent\": false,\r\n  \"height\": \"380\",\r\n    \"symbol\": \"SP:SPX\",\r\n  \"showIntervalTabs\": true,\r\n  \"displayMode\": \"single\",\r\n  \"locale\": \"en\",\r\n  \"colorTheme\": \"light\"\r\n}\r\n  <\/script>\r\n<\/div>\r\n\r\n<a class=\"brand-label\"><img decoding=\"async\" src=\"https:\/\/eralcapital.ltd\/wp-content\/uploads\/favicon1-1.svg\"\/><\/a>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/eralcapital.ltd\/en\/wp-json\/wp\/v2\/pages\/934"}],"collection":[{"href":"https:\/\/eralcapital.ltd\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eralcapital.ltd\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eralcapital.ltd\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eralcapital.ltd\/en\/wp-json\/wp\/v2\/comments?post=934"}],"version-history":[{"count":50,"href":"https:\/\/eralcapital.ltd\/en\/wp-json\/wp\/v2\/pages\/934\/revisions"}],"predecessor-version":[{"id":1834,"href":"https:\/\/eralcapital.ltd\/en\/wp-json\/wp\/v2\/pages\/934\/revisions\/1834"}],"wp:attachment":[{"href":"https:\/\/eralcapital.ltd\/en\/wp-json\/wp\/v2\/media?parent=934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}